{"id":1119,"date":"2020-02-24T09:21:00","date_gmt":"2020-02-24T08:21:00","guid":{"rendered":"https:\/\/pileouface.mecazen.lu\/blog\/?p=1119"},"modified":"2024-09-05T18:48:05","modified_gmt":"2024-09-05T16:48:05","slug":"comment-le-liquide-de-frein-est-il-contamine","status":"publish","type":"post","link":"https:\/\/mecazen.fr\/blog\/comment-le-liquide-de-frein-est-il-contamine\/","title":{"rendered":"Comment le liquide de frein est-il contamin\u00e9\u2009?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Le liquide de frein<\/strong> joue un r\u00f4le important dans le <strong>syst\u00e8me de freinage<\/strong>. C\u2019est lui qui assure le transfert de la force de freinages vers les pistons qui poussent <a href=\"https:\/\/mecazen.fr\/reparation-mecanique\/remplacement-plaquette-de-frein-et-disque\">les plaquettes de frein<\/a>. Sans ce fluide hydraulique, le frein ne marche pas, m\u00eame si vous appuyez comme un forcen\u00e9 sur la p\u00e9dale. Il y a deux cas o\u00f9 le liquide de frein est HS. Primo, la fuite qui fait que le fluide n\u2019est plus en quantit\u00e9 suffisante. La contamination par de l\u2019eau ou de la salet\u00e9 qui fait qu\u2019il a perdu ses propri\u00e9t\u00e9s. Dans les deux cas, le <a href=\"https:\/\/mecazen.fr\/reparation-mecanique\/remplacement-liquide-de-freins\">changement de liquide de frein<\/a> est primordial. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large td-caption-align-\/storage\/wordpress\/shared\/2024\/09\/AdobeStock_449726238_11zon.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"\/storage\/wordpress\/shared\/2024\/09\/AdobeStock_449726238_11zon-1024x682.jpeg\" alt=\"liquide de frein\" class=\"wp-image-5008\" srcset=\"\/storage\/wordpress\/shared\/2024\/09\/AdobeStock_449726238_11zon-1024x682.jpeg 1024w, \/storage\/wordpress\/shared\/2024\/09\/AdobeStock_449726238_11zon-300x200.jpeg 300w, \/storage\/wordpress\/shared\/2024\/09\/AdobeStock_449726238_11zon-768x512.jpeg 768w, \/storage\/wordpress\/shared\/2024\/09\/AdobeStock_449726238_11zon-1536x1024.jpeg 1536w, \/storage\/wordpress\/shared\/2024\/09\/AdobeStock_449726238_11zon-696x464.jpeg 696w, \/storage\/wordpress\/shared\/2024\/09\/AdobeStock_449726238_11zon-1068x712.jpeg 1068w, \/storage\/wordpress\/shared\/2024\/09\/AdobeStock_449726238_11zon-630x420.jpeg 630w, \/storage\/wordpress\/shared\/2024\/09\/AdobeStock_449726238_11zon.jpeg 1715w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_80 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire :<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/mecazen.fr\/blog\/comment-le-liquide-de-frein-est-il-contamine\/#Pourquoi_le_liquide_de_frein_est-il_susceptible_detre_contamine%E2%80%89\" >Pourquoi le liquide de frein est-il susceptible d\u2019\u00eatre contamin\u00e9\u2009?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/mecazen.fr\/blog\/comment-le-liquide-de-frein-est-il-contamine\/#Quelles_sont_les_consequences_de_la_contamination_de_liquide_de_frein%E2%80%89\" >Quelles sont les cons\u00e9quences de la contamination de liquide de frein\u2009?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/mecazen.fr\/blog\/comment-le-liquide-de-frein-est-il-contamine\/#Comment_eviter_la_contamination_de_liquide_de_frein%E2%80%89\" >Comment \u00e9viter la contamination de liquide de frein\u2009?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/mecazen.fr\/blog\/comment-le-liquide-de-frein-est-il-contamine\/#Nos_conseils\" >Nos conseils<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Pourquoi_le_liquide_de_frein_est-il_susceptible_detre_contamine%E2%80%89\"><\/span>Pourquoi le liquide de frein est-il susceptible d\u2019\u00eatre contamin\u00e9\u2009? <span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le liquide de frein poss\u00e8de des\ncaract\u00e9ristiques avantageuses par rapport \u00e0 d\u2019autres fluides. Il est\nincompressible, c\u2019est-\u00e0-dire que son volume ne peut \u00eatre r\u00e9duit par pression.\nIl r\u00e9siste \u00e9galement \u00e0 de tr\u00e8s fortes temp\u00e9ratures. Il faut jusqu\u2019\u00e0 plus de 200&nbsp;\u00b0C\npour le faire bouillir. C\u2019est lui qui transmet la puissance n\u00e9cessaire pour\narr\u00eater le v\u00e9hicule. Et il r\u00e9siste \u00e0 des temp\u00e9ratures \u00e9lev\u00e9es qui r\u00e9sultent de\nla friction entre plaquettes et le disque. <\/p>\n\n\n\n<div class=\"action_bloc\" style=\"background: #e8eff0;text-align: center;padding: 1rem;border-radius: 10px;box-shadow: 0px 0px 5px #ccc;margin-bottom: 1rem;\">\n<p style=\"font-weight: bold;font-size: 20px;margin-bottom: 10px;\">Trouver le meilleur devis imm\u00e9diatement<\/p>\n<a href=\"https:\/\/mecazen.fr\/\" class=\"\" style=\"background: #1cbbc1;color: #000;display: block;text-align: center;border-radius: 2rem;font-weight: bold;padding: .5rem;width: 80%;margin: auto;\">Comparez les prix des garages autour de moi\n<\/a>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Mais le liquide de frein dispose\naussi de points faibles. Il est hygroscopique, c\u2019est-\u00e0-dire qu\u2019il absorbe l\u2019<strong>humidit\u00e9<\/strong> de l\u2019air. Il est \u00e9galement\nhydrophile, ce qui veut dire qu\u2019il peut se m\u00e9langer \u00e0 l\u2019eau. L\u2019humidit\u00e9 peut\nprovenir des lignes hydrauliques. On note \u00e9galement l\u2019infiltration des <strong>particules ind\u00e9sirables<\/strong> d\u2019origines\ndiverses. Le <a href=\"https:\/\/mecazen.fr\/carnet-entretien-auto\/renault\/kadjar\/remplacement-plaquette-de-frein-et-disque\">remplacement\nde syst\u00e8me<\/a> de freinage, purge ne respectant pas les conditions de propret\u00e9,\nrouilles dues \u00e0 l\u2019humidit\u00e9\u2026 sont autant de sources de contamination. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quelles_sont_les_consequences_de_la_contamination_de_liquide_de_frein%E2%80%89\"><\/span>Quelles sont les cons\u00e9quences de la contamination de liquide de frein\u2009?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019eau n\u2019a pas la m\u00eame caract\u00e9ristique que le <strong>fluide hydraulique de frein<\/strong>. Il bout \u00e0 100&nbsp;\u00b0C. Ce qui fait qu\u2019\u00e0 la temp\u00e9rature \u00e9lev\u00e9e de freinage, elle s\u2019\u00e9vapore et se transforme en bulle d\u2019air. Or, l\u2019air est compressible et rend le liquide plus mou.L\u2019humidit\u00e9 entraine \u00e9galement une <strong>d\u00e9gradation chimique<\/strong> du <strong>liquide de frein<\/strong>. La rouille et la d\u00e9composition se forment \u00e0 l\u2019int\u00e9rieur du circuit de freinage, ce qui rend le <strong>liquide de frein sale<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toutes ces infiltrations d\u2019eau et de r\u00e9sidus d\u00e9t\u00e9riorent le bon fonctionnement du frein. Ce dernier devient mou, la distance de freinage s\u2019allonge, et tout peut l\u00e2cher \u00e0 tout moment. Lorsque ce sympt\u00f4me se pr\u00e9sente, il faut soumettre la voiture \u00e0 un c<strong>ontr\u00f4le de freinage complet<\/strong>. Ensuite, il faut proc\u00e9der \u00e0 la <strong><a href=\"https:\/\/mecazen.fr\/reparation-mecanique\/remplacement-liquide-de-freins\">purge de liquide de frein<\/a><\/strong>.Tant que le frein ne pr\u00e9sente pas de signes de mauvais fonctionnement, il est difficile de connaitre l\u2019\u00e9tat exact du liquide de frein. C\u2019est pour cette raison que les constructeurs recommandent une purge tous les 2 ans ou tous les 20\u2009000&nbsp;km. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large td-caption-align-\/storage\/wordpress\/shared\/2024\/09\/AdobeStock_357243952_11zon.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"\/storage\/wordpress\/shared\/2024\/09\/AdobeStock_357243952_11zon-1024x682.jpeg\" alt=\"liquide de frein\" class=\"wp-image-5009\" srcset=\"\/storage\/wordpress\/shared\/2024\/09\/AdobeStock_357243952_11zon-1024x682.jpeg 1024w, \/storage\/wordpress\/shared\/2024\/09\/AdobeStock_357243952_11zon-300x200.jpeg 300w, \/storage\/wordpress\/shared\/2024\/09\/AdobeStock_357243952_11zon-768x512.jpeg 768w, \/storage\/wordpress\/shared\/2024\/09\/AdobeStock_357243952_11zon-1536x1024.jpeg 1536w, \/storage\/wordpress\/shared\/2024\/09\/AdobeStock_357243952_11zon-696x464.jpeg 696w, \/storage\/wordpress\/shared\/2024\/09\/AdobeStock_357243952_11zon-1068x712.jpeg 1068w, \/storage\/wordpress\/shared\/2024\/09\/AdobeStock_357243952_11zon-630x420.jpeg 630w, \/storage\/wordpress\/shared\/2024\/09\/AdobeStock_357243952_11zon.jpeg 1715w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Comment_eviter_la_contamination_de_liquide_de_frein%E2%80%89\"><\/span>Comment \u00e9viter la contamination de liquide de frein\u2009?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019<strong>emplacement du liquide de frein<\/strong> est cens\u00e9 le prot\u00e9ger contre l\u2019infiltration d\u2019humidit\u00e9 et de salet\u00e9. Mais dans la pratique, le syst\u00e8me n\u2019est pas aussi prot\u00e9g\u00e9 que \u00e7a. Toutefois, vous pouvez r\u00e9duire les risques de sa d\u00e9t\u00e9rioration avec les gestes suivants. <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Limiter le freinage<\/strong> dans les conditions extr\u00eames&nbsp;: les freinages avec charges lourdes, les freinages brusques \u00e0 haute vitesse, les mont\u00e9es et descentes en fortes pentes. <\/li><li>Faire attention lors des travaux sur <strong>le syst\u00e8me de freinage<\/strong>. La d\u00e9pose de certaines pi\u00e8ces rend le liquide plus expos\u00e9 \u00e0 l\u2019humidit\u00e9 et aux salet\u00e9s. <\/li><li>Respecter la propret\u00e9 pendant la purge&nbsp;: utiliser des accessoires propres et secs. <\/li><li>D\u00e9tecter <strong>la fuite de liquide de frein<\/strong> \u00e0 temps&nbsp;: le changement de la pression de la p\u00e9dale indique que votre liquide de frein a fuit\u00e9 ou qu\u2019il y a pr\u00e9sence de bulle d\u2019air. <\/li><li>Le t\u00e9moin antiblocage ou le t\u00e9moin de syst\u00e8me de freinage qui s\u2019allume indique que le niveau de liquide peut \u00eatre faible. <\/li><li><strong>V\u00e9rifier les flexibles de frein<\/strong> et le ma\u00eetre-cylindre qui peuvent \u00eatre la source de fuite. <\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Nos_conseils\"><\/span><a>Nos conseils <\/a><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Confiez les op\u00e9rations de maintenance et de remplacement de vos organes de freinage \u00e0 professionnel. <\/li><li>Utiliser un <strong>bon liquide de frein de type&nbsp;DOT4<\/strong> ou d\u2019une qualit\u00e9 sup\u00e9rieure. <\/li><li><a href=\"https:\/\/mecazen.fr\/reparation-mecanique\/remplacement-liquide-de-freins\">Remplacez le liquide de frein<\/a> lorsque vous changez les plaquettes et les disques. <\/li><\/ul>\n\n\n\n<div class=\"action_bloc\" style=\"background: #e8eff0;text-align: center;padding: 1rem;border-radius: 10px;box-shadow: 0px 0px 5px #ccc;margin-bottom: 1rem;\">\n<p style=\"font-weight: bold;font-size: 20px;margin-bottom: 10px;\">Trouver le meilleur devis imm\u00e9diatement<\/p>\n<a href=\"https:\/\/mecazen.fr\/\" class=\"\" style=\"background: #1cbbc1;color: #000;display: block;text-align: center;border-radius: 2rem;font-weight: bold;padding: .5rem;width: 80%;margin: auto;\">Comparez les prix des garages autour de moi\n<\/a>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le liquide de frein joue un r\u00f4le important dans le syst\u00e8me de freinage. C\u2019est lui qui assure le transfert de la force de freinages vers les pistons qui poussent les plaquettes de frein. Sans ce fluide hydraulique, le frein ne marche pas, m\u00eame si vous appuyez comme un forcen\u00e9 sur la p\u00e9dale. Il y a [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":1124,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[114],"tags":[],"class_list":["post-1119","post","type-post","status-publish","format-standard","has-post-thumbnail","category-conseils"],"acf":[],"_links":{"self":[{"href":"https:\/\/mecazen.fr\/blog\/wp-json\/wp\/v2\/posts\/1119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mecazen.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mecazen.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mecazen.fr\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/mecazen.fr\/blog\/wp-json\/wp\/v2\/comments?post=1119"}],"version-history":[{"count":2,"href":"https:\/\/mecazen.fr\/blog\/wp-json\/wp\/v2\/posts\/1119\/revisions"}],"predecessor-version":[{"id":5010,"href":"https:\/\/mecazen.fr\/blog\/wp-json\/wp\/v2\/posts\/1119\/revisions\/5010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mecazen.fr\/blog\/wp-json\/wp\/v2\/media\/1124"}],"wp:attachment":[{"href":"https:\/\/mecazen.fr\/blog\/wp-json\/wp\/v2\/media?parent=1119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mecazen.fr\/blog\/wp-json\/wp\/v2\/categories?post=1119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mecazen.fr\/blog\/wp-json\/wp\/v2\/tags?post=1119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}